{"id":538,"date":"2018-08-09T16:11:47","date_gmt":"2018-08-09T09:11:47","guid":{"rendered":"https:\/\/vgi:8890\/2018\/08\/09\/vgi-group-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%87%e0%b8%9a-q1-%e0%b8%9b%e0%b8%b5-61-62-%e0%b9%82%e0%b8%95%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%ab%e0%b8%a2%e0%b8%b8%e0%b8%94\/"},"modified":"2025-02-14T18:05:51","modified_gmt":"2025-02-14T11:05:51","slug":"vgi-group-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%87%e0%b8%9a-q1-%e0%b8%9b%e0%b8%b5-61-62-%e0%b9%82%e0%b8%95%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%ab%e0%b8%a2%e0%b8%b8%e0%b8%94","status":"publish","type":"post","link":"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/","title":{"rendered":"VGI Group \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e07\u0e1a Q1 \u0e1b\u0e35 61\/62 \u0e42\u0e15\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14!! \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e01\u0e23\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e2d\u0e01\u0e22\u0e4d\u0e49\u0e32\u0e1c\u0e49\u0e39\u0e19\u0e4d\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 O2O Solutions"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p class=\"Default\">\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e2b\u0e23\u0e37\u0e2d \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d(VGI) \u0e1c\u0e39\u0e49\u0e19\u0e33 Offline-to-Online (\u201cO2O\u201d) Solutions \u0e23\u0e32\u0e22\u0e41\u0e23\u0e01\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 1 \u0e1b\u0e35 61\/62\u00a0 (\u0e40\u0e21.\u0e22.-\u0e21\u0e34.\u0e22.61) \u0e17\u0e33\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e23\u0e27\u0e21 1,077\u00a0 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 26.5 % \u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e35\u0e01\u0e48\u0e2d\u0e19 \u0e41\u0e23\u0e07\u0e2b\u0e19\u0e38\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e21\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e42\u0e15\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e19\u0e2d\u0e01\u0e1a\u0e49\u0e32\u0e19 (OOH) \u0e41\u0e25\u0e30\u0e08\u0e32\u0e01\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e01\u0e25\u0e38\u0e48\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e42\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e36\u0e07\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07\u00a0<\/p>\n<p class=\"Default\">\u0e04\u0e38\u0e13\u0e40\u0e19\u0e25\u0e2a\u0e31\u0e19 \u0e40\u0e2b\u0e25\u0e35\u0e22\u0e07 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e1b\u0e35\u0e19\u0e35\u0e49\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 20 \u0e1b\u0e35 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e27\u0e34\u0e2a\u0e31\u0e22\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e40\u0e1b\u0e47\u0e19 \u201cPioneering Solutions for Tomorrow\u201d \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e22\u0e32\u0e22\u0e08\u0e32\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e19\u0e2d\u0e01\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e44\u0e27\u0e49\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48 \u0e2b\u0e23\u0e37\u0e2d O2O Solutions\u00a0 \u0e42\u0e14\u0e22\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e40\u0e23\u0e32\u0e04\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 O2O Solutions \u0e23\u0e32\u0e22\u0e41\u0e23\u0e01\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49\u0e04\u0e23\u0e1a\u0e17\u0e38\u0e01\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e01\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49\u0e04\u0e23\u0e1a\u0e17\u0e38\u0e01\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19 \u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e2d\u0e35\u0e42\u0e04\u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 (ecosystem) \u0e02\u0e2d\u0e07 VGI \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 3 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2b\u0e25\u0e31\u0e01 \u0e04\u0e37\u0e2d \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e19\u0e2d\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 (\u0e2a\u0e37\u0e48\u0e2d\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e2a\u0e37\u0e48\u0e2d\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e43\u0e19\u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19) \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e02\u0e2d\u0e07 \u0e41\u0e23\u0e1a\u0e1a\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e02\u0e2d\u0e07\u0e40\u0e04\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e2d\u0e47\u0e01\u0e40\u0e1e\u0e23\u0e2a \u0e41\u0e25\u0e30\u0e40\u0e14\u0e42\u0e21 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e38\u0e0d\u0e41\u0e08\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23\u00a0 \u00a0<\/p>\n<p class=\"Default\">\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e42\u0e21\u0e40\u0e14\u0e25\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e42\u0e1f\u0e01\u0e31\u0e2a\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e07\u0e1a\u0e42\u0e06\u0e29\u0e13\u0e32\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e17\u0e31\u0e49\u0e07 3 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e08\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e46 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e17\u0e35\u0e48\u0e41\u0e15\u0e48\u0e40\u0e14\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e42\u0e06\u0e29\u0e13\u0e32\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e42\u0e14\u0e22\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e42\u0e06\u0e29\u0e13\u0e32\u0e19\u0e31\u0e49\u0e19\u0e21\u0e31\u0e01\u0e41\u0e1b\u0e23\u0e1c\u0e31\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e2a\u0e20\u0e32\u0e27\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e04\u0e27\u0e49\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e1a\u0e48\u0e07\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e02\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e35\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b (e-Commerce) \u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e21\u0e32\u0e41\u0e23\u0e07 \u0e42\u0e14\u0e22\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e19\u0e35\u0e49\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49 VGI \u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e43\u0e19\u0e15\u0e25\u0e32\u0e14\u0e44\u0e14\u0e49\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19<\/p>\n<p class=\"Default\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e01\u0e25\u0e38\u0e48\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e30\u0e1e\u0e1a\u0e27\u0e48\u0e32 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e19\u0e2d\u0e01\u0e1a\u0e49\u0e32\u0e19 (OOH) \u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 997 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 32.1% \u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e35\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32 \u0e42\u0e14\u0e22\u0e04\u0e34\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e14\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 92.5% \u0e02\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e23\u0e27\u0e21\u0e43\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 1 \u0e1b\u0e35 2561\/62 \u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e15\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e16\u0e39\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e43\u0e19\u0e17\u0e38\u0e01\u0e01\u0e25\u0e38\u0e48\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e21\u0e35\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e08\u0e32\u0e01 Synergy \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 O2O Solutions, \u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19\u0e02\u0e2d\u0e07\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d, \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e1a\u0e34\u0e25\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e07\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e08\u0e32\u0e01\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e42\u0e04\u0e41\u0e21\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 (Co-Mass) \u0e42\u0e14\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e21\u0e2b\u0e32\u0e0a\u0e19 (MACO)<\/p>\n<p class=\"Default\">\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e21\u0e35\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 620 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 19.5% \u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e1b\u0e35\u0e01\u0e48\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e1a\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e35 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01 synergy \u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d O2O Solutions \u0e1a\u0e19 10 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1a\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e2a \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e01\u0e27\u0e48\u0e32 80 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 1 \u0e1b\u0e35 2561\/62<\/p>\n<p class=\"Default\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e21\u0e35\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 93 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 40.0% \u0e08\u0e32\u0e01\u0e1b\u0e35\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32 \u0e42\u0e14\u0e22\u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e2b\u0e25\u0e31\u0e01\u0e21\u0e32\u0e08\u0e32\u0e01\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e02\u0e36\u0e49\u0e19\u0e23\u0e32\u0e04\u0e32\u0e02\u0e2d\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e46 \u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e37\u0e48\u0e19\u0e46<\/p>\n<p class=\"Default\">\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 MACO \u0e22\u0e31\u0e07\u0e21\u0e35\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e17\u0e35\u0e48\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 284 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 67.4% \u0e2b\u0e23\u0e37\u0e2d 114\u00a0 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e35\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32 \u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e2b\u0e25\u0e31\u0e01\u0e21\u0e32\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e1a\u0e34\u0e25\u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e19\u0e27\u0e19 35 \u0e08\u0e2d \u0e41\u0e25\u0e30\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e07\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e40\u0e15\u0e47\u0e21\u0e1b\u0e35\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e04\u0e41\u0e21\u0e2a \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2560 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32<\/p>\n<p class=\"Default\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e25\u0e38\u0e48\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e21\u0e35\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 80 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e25\u0e14\u0e25\u0e07 17.2% \u0e08\u0e32\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e35\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32 \u0e04\u0e34\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e14\u0e2a\u0e48\u0e27\u0e19 7.5% \u0e02\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e2b\u0e25\u0e31\u0e01\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e25\u0e14\u0e25\u0e07\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 (project management) \u0e41\u0e15\u0e48\u0e2b\u0e32\u0e01\u0e21\u0e2d\u0e07\u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21\u0e41\u0e25\u0e49\u0e27 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e40\u0e1b\u0e47\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e42\u0e06\u0e29\u0e13\u0e32\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e27\u0e31\u0e14\u0e1c\u0e25\u0e44\u0e14\u0e49\u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e17\u0e35\u0e48\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u00a0 \u0e08\u0e36\u0e07\u0e19\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e1b\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u00a0<\/p>\n<p class=\"Default\">\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e22\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e2d\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e08\u0e32\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e25\u0e48\u0e32\u0e27\u0e21\u0e32\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19 \u0e19\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e35 2561\/62\u00a0 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e1b\u0e35 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e35\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 4,400 \u0e16\u0e36\u0e07 4,600 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e42\u0e14\u0e22\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e33\u0e44\u0e23\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u00a0 20-25% \u0e15\u0e32\u0e21\u0e25\u0e33\u0e14\u0e31\u0e1a<\/p>\n<p class=\"Default\">\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 19 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2561 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e17\u0e22\u0e38\u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e1a\u0e35\u0e1a\u0e35\u0e17\u0e35\u0e27\u0e35) \u0e23\u0e48\u0e27\u0e21\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e23\u0e48\u0e27\u0e21\u0e17\u0e38\u0e19 \u0e0a\u0e37\u0e48\u0e2d \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1a\u0e35\u0e27\u0e35 \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e2d\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e42\u0e14\u0e22\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e2a\u0e31\u0e14\u0e2a\u0e48\u0e27\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e25\u0e30 50% \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e14\u0e32\u0e23\u0e32\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u00a0 \u0e42\u0e14\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e0a\u0e48\u0e2d\u0e07 7 \u0e20\u0e32\u0e22\u0e43\u0e19 BVTV \u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 O2O Solutions\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u00a0\u00a0<\/p>\n<p class=\"Default\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e02\u0e2d\u0e07 VGI \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 1 (\u201cVGI-W1\u201d) \u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38\u0e25\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2561 \u0e42\u0e14\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e41\u0e1b\u0e25\u0e07\u0e2a\u0e20\u0e32\u0e1e VGI-W1 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 8,618 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17\u00a0 \u0e2b\u0e23\u0e37\u0e2d 72% \u0e02\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e07\u0e34\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e08\u0e32\u0e01 VGI-W1 \u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e19\u0e33\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e40\u0e04\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e2d\u0e47\u0e01\u0e40\u0e1e\u0e23\u0e2a \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e40\u0e07\u0e34\u0e19\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e44\u0e14\u0e49\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e08\u0e30\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e17\u0e38\u0e19\u0e02\u0e2d\u0e07 MACO \u0e15\u0e32\u0e21\u0e2a\u0e31\u0e14\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 (Right Offerings) \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e02\u0e22\u0e32\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u00a0 \u00a0\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e25\u0e48\u0e32\u0e27.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<hr class=\"my-4\" \/><strong>\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e19\u0e31\u0e01\u0e25\u0e07\u0e17\u0e38\u0e19\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/strong><br \/>\n\t\t\u0e0a\u0e32\u0e21\u0e32 \u0e40\u0e28\u0e27\u0e15\u0e1a\u0e14\u0e35<br \/>\n\t\t\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1d\u0e48\u0e32\u0e22\u0e19\u0e31\u0e01\u0e25\u0e07\u0e17\u0e38\u0e19\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<br \/>\n\t\t<a href=\"mailto:ir@vgi.co.th\">ir@vgi.co.th<\/a>\n","protected":false},"excerpt":{"rendered":"<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e2b\u0e23\u0e37\u0e2d \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d(V [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2128,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VGI Group \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e07\u0e1a Q1 \u0e1b\u0e35 61\/62 \u0e42\u0e15\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14!! \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e01\u0e23\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e2d\u0e01\u0e22\u0e4d\u0e49\u0e32\u0e1c\u0e49\u0e39\u0e19\u0e4d\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 O2O Solutions - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VGI Group \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e07\u0e1a Q1 \u0e1b\u0e35 61\/62 \u0e42\u0e15\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14!! \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e01\u0e23\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e2d\u0e01\u0e22\u0e4d\u0e49\u0e32\u0e1c\u0e49\u0e39\u0e19\u0e4d\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 O2O Solutions - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\" \/>\n<meta property=\"og:description\" content=\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e2b\u0e23\u0e37\u0e2d \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d(V [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-09T09:11:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-14T11:05:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2018\/08\/s_9354610-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"735\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paween\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paween\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/538\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/538\\\/\"},\"author\":{\"name\":\"Paween\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#\\\/schema\\\/person\\\/a41cc997ff08830763994cf1238499e2\"},\"headline\":\"VGI Group \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e07\u0e1a Q1 \u0e1b\u0e35 61\\\/62 \u0e42\u0e15\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14!! \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e01\u0e23\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e2d\u0e01\u0e22\u0e4d\u0e49\u0e32\u0e1c\u0e49\u0e39\u0e19\u0e4d\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 O2O Solutions\",\"datePublished\":\"2018-08-09T09:11:47+00:00\",\"dateModified\":\"2025-02-14T11:05:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/538\\\/\"},\"wordCount\":56,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/538\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vgi.co.th\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/s_9354610-1.jpg\",\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\"],\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/538\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/538\\\/\",\"url\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/538\\\/\",\"name\":\"VGI Group \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e07\u0e1a Q1 \u0e1b\u0e35 61\\\/62 \u0e42\u0e15\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14!! \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e01\u0e23\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e2d\u0e01\u0e22\u0e4d\u0e49\u0e32\u0e1c\u0e49\u0e39\u0e19\u0e4d\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 O2O Solutions - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/538\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/538\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vgi.co.th\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/s_9354610-1.jpg\",\"datePublished\":\"2018-08-09T09:11:47+00:00\",\"dateModified\":\"2025-02-14T11:05:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/538\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/538\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/538\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vgi.co.th\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/s_9354610-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vgi.co.th\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/s_9354610-1.jpg\",\"width\":735,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/538\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VGI Group \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e07\u0e1a Q1 \u0e1b\u0e35 61\\\/62 \u0e42\u0e15\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14!! \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e01\u0e23\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e2d\u0e01\u0e22\u0e4d\u0e49\u0e32\u0e1c\u0e49\u0e39\u0e19\u0e4d\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 O2O Solutions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/\",\"name\":\"VGI Public Company Limited\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#organization\",\"name\":\"VGI Public Company Limited\",\"url\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vgi.co.th\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ms-icon-310x310-1.png\",\"contentUrl\":\"https:\\\/\\\/www.vgi.co.th\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ms-icon-310x310-1.png\",\"width\":310,\"height\":310,\"caption\":\"VGI Public Company Limited\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#\\\/schema\\\/person\\\/a41cc997ff08830763994cf1238499e2\",\"name\":\"Paween\",\"sameAs\":[\"http:\\\/\\\/www.vgi.co.th\\\/wp\"],\"url\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/author\\\/pingno4design-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VGI Group \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e07\u0e1a Q1 \u0e1b\u0e35 61\/62 \u0e42\u0e15\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14!! \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e01\u0e23\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e2d\u0e01\u0e22\u0e4d\u0e49\u0e32\u0e1c\u0e49\u0e39\u0e19\u0e4d\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 O2O Solutions - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/","og_locale":"th_TH","og_type":"article","og_title":"VGI Group \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e07\u0e1a Q1 \u0e1b\u0e35 61\/62 \u0e42\u0e15\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14!! \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e01\u0e23\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e2d\u0e01\u0e22\u0e4d\u0e49\u0e32\u0e1c\u0e49\u0e39\u0e19\u0e4d\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 O2O Solutions - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)","og_description":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e2b\u0e23\u0e37\u0e2d \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d(V [&hellip;]","og_url":"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/","og_site_name":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)","article_published_time":"2018-08-09T09:11:47+00:00","article_modified_time":"2025-02-14T11:05:51+00:00","og_image":[{"width":735,"height":450,"url":"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2018\/08\/s_9354610-1.jpg","type":"image\/jpeg"}],"author":"Paween","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Paween","Est. reading time":"2 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/#article","isPartOf":{"@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/"},"author":{"name":"Paween","@id":"https:\/\/www.vgi.co.th\/th\/#\/schema\/person\/a41cc997ff08830763994cf1238499e2"},"headline":"VGI Group \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e07\u0e1a Q1 \u0e1b\u0e35 61\/62 \u0e42\u0e15\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14!! \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e01\u0e23\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e2d\u0e01\u0e22\u0e4d\u0e49\u0e32\u0e1c\u0e49\u0e39\u0e19\u0e4d\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 O2O Solutions","datePublished":"2018-08-09T09:11:47+00:00","dateModified":"2025-02-14T11:05:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/"},"wordCount":56,"commentCount":0,"publisher":{"@id":"https:\/\/www.vgi.co.th\/th\/#organization"},"image":{"@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2018\/08\/s_9354610-1.jpg","articleSection":["\u0e02\u0e48\u0e32\u0e27"],"inLanguage":"th","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/","url":"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/","name":"VGI Group \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e07\u0e1a Q1 \u0e1b\u0e35 61\/62 \u0e42\u0e15\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14!! \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e01\u0e23\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e2d\u0e01\u0e22\u0e4d\u0e49\u0e32\u0e1c\u0e49\u0e39\u0e19\u0e4d\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 O2O Solutions - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)","isPartOf":{"@id":"https:\/\/www.vgi.co.th\/th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/#primaryimage"},"image":{"@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2018\/08\/s_9354610-1.jpg","datePublished":"2018-08-09T09:11:47+00:00","dateModified":"2025-02-14T11:05:51+00:00","breadcrumb":{"@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/#primaryimage","url":"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2018\/08\/s_9354610-1.jpg","contentUrl":"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2018\/08\/s_9354610-1.jpg","width":735,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/538\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vgi.co.th\/th\/"},{"@type":"ListItem","position":2,"name":"VGI Group \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e07\u0e1a Q1 \u0e1b\u0e35 61\/62 \u0e42\u0e15\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14!! \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e01\u0e23\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e2d\u0e01\u0e22\u0e4d\u0e49\u0e32\u0e1c\u0e49\u0e39\u0e19\u0e4d\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 O2O Solutions"}]},{"@type":"WebSite","@id":"https:\/\/www.vgi.co.th\/th\/#website","url":"https:\/\/www.vgi.co.th\/th\/","name":"VGI Public Company Limited","description":"","publisher":{"@id":"https:\/\/www.vgi.co.th\/th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vgi.co.th\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.vgi.co.th\/th\/#organization","name":"VGI Public Company Limited","url":"https:\/\/www.vgi.co.th\/th\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.vgi.co.th\/th\/#\/schema\/logo\/image\/","url":"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2020\/07\/ms-icon-310x310-1.png","contentUrl":"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2020\/07\/ms-icon-310x310-1.png","width":310,"height":310,"caption":"VGI Public Company Limited"},"image":{"@id":"https:\/\/www.vgi.co.th\/th\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vgi.co.th\/th\/#\/schema\/person\/a41cc997ff08830763994cf1238499e2","name":"Paween","sameAs":["http:\/\/www.vgi.co.th\/wp"],"url":"https:\/\/www.vgi.co.th\/th\/author\/pingno4design-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/posts\/538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/comments?post=538"}],"version-history":[{"count":2,"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/posts\/538\/revisions"}],"predecessor-version":[{"id":17160,"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/posts\/538\/revisions\/17160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/media\/2128"}],"wp:attachment":[{"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/media?parent=538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/categories?post=538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/tags?post=538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}