{"id":6359,"date":"2021-02-18T15:56:44","date_gmt":"2021-02-18T08:56:44","guid":{"rendered":"http:\/\/www.vgi.co.th\/?p=6359"},"modified":"2021-02-18T15:56:46","modified_gmt":"2021-02-18T08:56:46","slug":"vgi-%e0%b8%9c%e0%b8%87%e0%b8%b2%e0%b8%94-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%94%e0%b8%b3%e0%b9%80%e0%b8%99%e0%b8%b4%e0%b8%99","status":"publish","type":"post","link":"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/","title":{"rendered":"VGI \u0e1c\u0e07\u0e32\u0e14! \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 3 \u0e1b\u0e35 63\/64 \u0e1e\u0e25\u0e34\u0e01\u0e21\u0e35\u0e01\u0e33\u0e44\u0e23 713 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17!!\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e2b\u0e23\u0e37\u0e2d \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d (\u201cVGI\u201d) \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 Offline-to-Online (\u201cO2O\u201d) \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e1c\u0e22\u0e1c\u0e25\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 3 \u0e1b\u0e35 2563\/64 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e23\u0e34\u0e48\u0e21\u0e1f\u0e37\u0e49\u0e19\u0e15\u0e31\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e1a\u0e27\u0e01\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e02\u0e32\u0e22\u0e2b\u0e38\u0e49\u0e19 IPO \u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e04\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) (\u201cKEX\u201d) \u0e08\u0e36\u0e07\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49 VGI \u0e1e\u0e25\u0e34\u0e01\u0e21\u0e35\u0e01\u0e33\u0e44\u0e23\u0e2a\u0e38\u0e17\u0e18\u0e34 713 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e0a\u0e14\u0e40\u0e0a\u0e22\u0e01\u0e32\u0e23\u0e02\u0e32\u0e14\u0e17\u0e38\u0e19\u0e2a\u0e30\u0e2a\u0e21\u0e43\u0e19\u0e04\u0e23\u0e36\u0e48\u0e07\u0e1b\u0e35\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07\u0e1b\u0e35 2563\/64 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e04\u0e38\u0e13\u0e40\u0e19\u0e25\u0e2a\u0e31\u0e19 \u0e40\u0e2b\u0e25\u0e35\u0e22\u0e07 \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e0d\u0e48 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07 COVID-19 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e44\u0e17\u0e22\u0e43\u0e19\u0e1b\u0e35 2563 \u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e2b\u0e14\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e25\u0e1a\u0e15\u0e48\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a\u0e08\u0e48\u0e32\u0e22\u0e43\u0e0a\u0e49\u0e2a\u0e2d\u0e22\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e08\u0e19\u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e25\u0e14\u0e07\u0e1a\u0e42\u0e06\u0e29\u0e13\u0e32\u0e08\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01\u0e15\u0e48\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e40\u0e23\u0e34\u0e48\u0e21\u0e21\u0e35\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e01\u0e32\u0e23\u0e1f\u0e37\u0e49\u0e19\u0e15\u0e31\u0e27\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 \u2013 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32 \u0e2a\u0e37\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e32\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e02\u0e49\u0e2d\u0e08\u0e33\u0e01\u0e31\u0e14\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e33\u0e43\u0e2b\u0e49 VGI \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e25\u0e34\u0e01\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e17\u0e33\u0e01\u0e33\u0e44\u0e23\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e17\u0e35\u0e48 713 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e0a\u0e14\u0e40\u0e0a\u0e22\u0e01\u0e32\u0e23\u0e02\u0e32\u0e14\u0e17\u0e38\u0e19\u0e2a\u0e30\u0e2a\u0e21\u0e43\u0e19\u0e04\u0e23\u0e36\u0e48\u0e07\u0e1b\u0e35\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07\u0e1b\u0e35 2563\/64 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e23\u0e27\u0e21\u0e17\u0e35\u0e48 680 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e19\u0e35\u0e49\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e19\u0e2d\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e35\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 458 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e21\u0e35\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 222 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17<br>\u2003<br>\u0e14\u0e49\u0e32\u0e19\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17<br>\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e22\u0e31\u0e07\u0e04\u0e07\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e42\u0e06\u0e29\u0e13\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e43\u0e19\u0e17\u0e38\u0e01\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e41\u0e23\u0e1a\u0e1a\u0e34\u0e17 \u0e44\u0e25\u0e19\u0e4c\u0e40\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 (\u201cRLP\u201d) \u0e44\u0e14\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e21\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e21\u0e40\u0e07\u0e34\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 app-to-app \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 RLP e-wallet \u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e19\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a 3 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 SCB EASY, K PLUS \u0e41\u0e25\u0e30 KMA \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23 IPO \u0e02\u0e2d\u0e07 KEX \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e27\u0e31\u0e19\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e21\u0e35\u0e23\u0e32\u0e04\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19\u0e16\u0e36\u0e07 132 % \u0e08\u0e32\u0e01\u0e23\u0e32\u0e04\u0e32 IPO \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e19\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e42\u0e14\u0e22\u0e21\u0e35 VGI \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e01\u0e32\u0e23 IPO \u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e43\u0e19\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49 (awareness) \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21 (engagement) \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 (conversion) \u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e25\u0e07\u0e17\u0e38\u0e19\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e43\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e02\u0e2d\u0e07 KEX \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c Offline-to-Online (\u201cO2O\u201d) \u0e02\u0e2d\u0e07 VGI \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e15\u0e48\u0e2d\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e23\u0e30\u0e25\u0e2d\u0e01\u0e43\u0e2b\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04 COVID-19 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e25\u0e48\u0e32\u0e0a\u0e49\u0e32\u0e43\u0e19\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 \u0e44\u0e14\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e23\u0e07\u0e01\u0e14\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e02\u0e2d\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e44\u0e17\u0e22\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e44\u0e14\u0e49\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14 \u0e04\u0e27\u0e1a\u0e04\u0e39\u0e48\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c New Normal \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e20\u0e32\u0e1e\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1f\u0e37\u0e49\u0e19\u0e15\u0e31\u0e27\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e15\u0e48\u0e2d\u0e27\u0e34\u0e01\u0e24\u0e15\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e27\u0e48\u0e32 VGI \u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e19\u0e35\u0e49 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e21\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u201d \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e0d\u0e48 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 15 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2564 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e21\u0e35\u0e21\u0e15\u0e34\u0e2d\u0e19\u0e38\u0e21\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e08\u0e48\u0e32\u0e22\u0e40\u0e07\u0e34\u0e19\u0e1b\u0e31\u0e19\u0e1c\u0e25\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e25\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e04\u0e23\u0e36\u0e48\u0e07\u0e1b\u0e35\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e23\u0e27\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 172.2 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17\u0e43\u0e19\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e2b\u0e38\u0e49\u0e19\u0e25\u0e30 0.02 \u0e1a\u0e32\u0e17 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e1b\u0e34\u0e14\u0e2a\u0e21\u0e38\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2564 (Record Date) \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e08\u0e48\u0e32\u0e22\u0e40\u0e07\u0e34\u0e19\u0e1b\u0e31\u0e19\u0e1c\u0e25\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e25\u0e04\u0e37\u0e2d 15 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2564<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e2b\u0e23\u0e37\u0e2d \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d (\u201cVGI\u201d) \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e01\u0e32 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6360,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-6359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VGI \u0e1c\u0e07\u0e32\u0e14! \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 3 \u0e1b\u0e35 63\/64 \u0e1e\u0e25\u0e34\u0e01\u0e21\u0e35\u0e01\u0e33\u0e44\u0e23 713 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17!!\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22 - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VGI \u0e1c\u0e07\u0e32\u0e14! \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 3 \u0e1b\u0e35 63\/64 \u0e1e\u0e25\u0e34\u0e01\u0e21\u0e35\u0e01\u0e33\u0e44\u0e23 713 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17!!\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22 - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\" \/>\n<meta property=\"og:description\" content=\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e2b\u0e23\u0e37\u0e2d \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d (\u201cVGI\u201d) \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e01\u0e32 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-18T08:56:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-18T08:56:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2021\/02\/Thumbnail735x450_2020_Q3_TH.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"735\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nisakorn Kanharat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nisakorn Kanharat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/6359\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/6359\\\/\"},\"author\":{\"name\":\"Nisakorn Kanharat\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#\\\/schema\\\/person\\\/4eef5a087599ff6d39def5f579cf1b41\"},\"headline\":\"VGI \u0e1c\u0e07\u0e32\u0e14! \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 3 \u0e1b\u0e35 63\\\/64 \u0e1e\u0e25\u0e34\u0e01\u0e21\u0e35\u0e01\u0e33\u0e44\u0e23 713 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17!!\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\",\"datePublished\":\"2021-02-18T08:56:44+00:00\",\"dateModified\":\"2021-02-18T08:56:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/6359\\\/\"},\"wordCount\":38,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/6359\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vgi.co.th\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Thumbnail735x450_2020_Q3_TH.jpg\",\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\"],\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/6359\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/6359\\\/\",\"url\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/6359\\\/\",\"name\":\"VGI \u0e1c\u0e07\u0e32\u0e14! \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 3 \u0e1b\u0e35 63\\\/64 \u0e1e\u0e25\u0e34\u0e01\u0e21\u0e35\u0e01\u0e33\u0e44\u0e23 713 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17!!\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22 - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/6359\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/6359\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vgi.co.th\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Thumbnail735x450_2020_Q3_TH.jpg\",\"datePublished\":\"2021-02-18T08:56:44+00:00\",\"dateModified\":\"2021-02-18T08:56:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/6359\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/6359\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/6359\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vgi.co.th\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Thumbnail735x450_2020_Q3_TH.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vgi.co.th\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Thumbnail735x450_2020_Q3_TH.jpg\",\"width\":735,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/news\\\/detail\\\/6359\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VGI \u0e1c\u0e07\u0e32\u0e14! \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 3 \u0e1b\u0e35 63\\\/64 \u0e1e\u0e25\u0e34\u0e01\u0e21\u0e35\u0e01\u0e33\u0e44\u0e23 713 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17!!\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/\",\"name\":\"VGI Public Company Limited\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#organization\",\"name\":\"VGI Public Company Limited\",\"url\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vgi.co.th\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ms-icon-310x310-1.png\",\"contentUrl\":\"https:\\\/\\\/www.vgi.co.th\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ms-icon-310x310-1.png\",\"width\":310,\"height\":310,\"caption\":\"VGI Public Company Limited\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/#\\\/schema\\\/person\\\/4eef5a087599ff6d39def5f579cf1b41\",\"name\":\"Nisakorn Kanharat\",\"url\":\"https:\\\/\\\/www.vgi.co.th\\\/th\\\/author\\\/nisakornvgi-co-th\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VGI \u0e1c\u0e07\u0e32\u0e14! \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 3 \u0e1b\u0e35 63\/64 \u0e1e\u0e25\u0e34\u0e01\u0e21\u0e35\u0e01\u0e33\u0e44\u0e23 713 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17!!\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22 - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/","og_locale":"th_TH","og_type":"article","og_title":"VGI \u0e1c\u0e07\u0e32\u0e14! \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 3 \u0e1b\u0e35 63\/64 \u0e1e\u0e25\u0e34\u0e01\u0e21\u0e35\u0e01\u0e33\u0e44\u0e23 713 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17!!\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22 - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)","og_description":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e2b\u0e23\u0e37\u0e2d \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d (\u201cVGI\u201d) \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e01\u0e32 [&hellip;]","og_url":"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/","og_site_name":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)","article_published_time":"2021-02-18T08:56:44+00:00","article_modified_time":"2021-02-18T08:56:46+00:00","og_image":[{"width":735,"height":450,"url":"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2021\/02\/Thumbnail735x450_2020_Q3_TH.jpg","type":"image\/jpeg"}],"author":"Nisakorn Kanharat","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Nisakorn Kanharat","Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/#article","isPartOf":{"@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/"},"author":{"name":"Nisakorn Kanharat","@id":"https:\/\/www.vgi.co.th\/th\/#\/schema\/person\/4eef5a087599ff6d39def5f579cf1b41"},"headline":"VGI \u0e1c\u0e07\u0e32\u0e14! \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 3 \u0e1b\u0e35 63\/64 \u0e1e\u0e25\u0e34\u0e01\u0e21\u0e35\u0e01\u0e33\u0e44\u0e23 713 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17!!\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22","datePublished":"2021-02-18T08:56:44+00:00","dateModified":"2021-02-18T08:56:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/"},"wordCount":38,"commentCount":0,"publisher":{"@id":"https:\/\/www.vgi.co.th\/th\/#organization"},"image":{"@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2021\/02\/Thumbnail735x450_2020_Q3_TH.jpg","articleSection":["\u0e02\u0e48\u0e32\u0e27"],"inLanguage":"th","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/","url":"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/","name":"VGI \u0e1c\u0e07\u0e32\u0e14! \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 3 \u0e1b\u0e35 63\/64 \u0e1e\u0e25\u0e34\u0e01\u0e21\u0e35\u0e01\u0e33\u0e44\u0e23 713 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17!!\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22 - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e35\u0e08\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)","isPartOf":{"@id":"https:\/\/www.vgi.co.th\/th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/#primaryimage"},"image":{"@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2021\/02\/Thumbnail735x450_2020_Q3_TH.jpg","datePublished":"2021-02-18T08:56:44+00:00","dateModified":"2021-02-18T08:56:46+00:00","breadcrumb":{"@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/#primaryimage","url":"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2021\/02\/Thumbnail735x450_2020_Q3_TH.jpg","contentUrl":"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2021\/02\/Thumbnail735x450_2020_Q3_TH.jpg","width":735,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.vgi.co.th\/th\/news\/detail\/6359\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vgi.co.th\/th\/"},{"@type":"ListItem","position":2,"name":"VGI \u0e1c\u0e07\u0e32\u0e14! \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a 3 \u0e1b\u0e35 63\/64 \u0e1e\u0e25\u0e34\u0e01\u0e21\u0e35\u0e01\u0e33\u0e44\u0e23 713 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17!!\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22"}]},{"@type":"WebSite","@id":"https:\/\/www.vgi.co.th\/th\/#website","url":"https:\/\/www.vgi.co.th\/th\/","name":"VGI Public Company Limited","description":"","publisher":{"@id":"https:\/\/www.vgi.co.th\/th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vgi.co.th\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.vgi.co.th\/th\/#organization","name":"VGI Public Company Limited","url":"https:\/\/www.vgi.co.th\/th\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.vgi.co.th\/th\/#\/schema\/logo\/image\/","url":"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2020\/07\/ms-icon-310x310-1.png","contentUrl":"https:\/\/www.vgi.co.th\/wp-content\/uploads\/2020\/07\/ms-icon-310x310-1.png","width":310,"height":310,"caption":"VGI Public Company Limited"},"image":{"@id":"https:\/\/www.vgi.co.th\/th\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vgi.co.th\/th\/#\/schema\/person\/4eef5a087599ff6d39def5f579cf1b41","name":"Nisakorn Kanharat","url":"https:\/\/www.vgi.co.th\/th\/author\/nisakornvgi-co-th\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/posts\/6359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/comments?post=6359"}],"version-history":[{"count":1,"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/posts\/6359\/revisions"}],"predecessor-version":[{"id":6364,"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/posts\/6359\/revisions\/6364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/media\/6360"}],"wp:attachment":[{"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/media?parent=6359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/categories?post=6359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vgi.co.th\/th\/wp-json\/wp\/v2\/tags?post=6359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}